{"id":351,"date":"2017-12-04T11:04:10","date_gmt":"2017-12-04T13:04:10","guid":{"rendered":"https:\/\/holhos.com.br\/blog\/?p=351"},"modified":"2025-06-17T14:30:55","modified_gmt":"2025-06-17T17:30:55","slug":"o-que-e-cirurgia-refrativa","status":"publish","type":"post","link":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/","title":{"rendered":"O que \u00e9 cirurgia refrativa? Conhe\u00e7a os benef\u00edcios do procedimento"},"content":{"rendered":"<p><img decoding=\"async\" class=\"size-full wp-image-358\" src=\"https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-626535710.jpg\" alt=\"\" width=\"1256\" height=\"100%\" srcset=\"https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-626535710.jpg 1256w, https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-626535710-300x199.jpg 300w, https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-626535710-768x511.jpg 768w, https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-626535710-1024x681.jpg 1024w\" sizes=\"(max-width: 1256px) 100vw, 1256px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 imaginou analisar uma planilha e enxergar todos os n\u00fameros fora de foco? E n\u00e3o conseguir ler o que a professora escreve no quadro?\u00a0Outro problema diz respeito \u00e0 pr\u00e1tica de esportes. Ter de for\u00e7ar a vista para jogar aquela partida de futebol ou de v\u00f4lei com os amigos sem deixar passar a bola por debaixo do nariz.\u00a0 <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essas atividades, t\u00e3o importantes do dia a dia, tornam-se ainda mais dif\u00edceis se acompanhadas de desconforto e mal-estar pela baixa qualidade da vis\u00e3o.\u00a0Dificuldades que muita gente enfrenta, sem saber como \u00e9 poss\u00edvel super\u00e1-las.\u00a0<\/span><span style=\"font-weight: 400;\">Em rela\u00e7\u00e3o \u00e0 escola, essa dificuldade pode significar desconforto para ler e copiar a mat\u00e9ria no quadro, o que pode, por consequ\u00eancia, diminuir o aprendizado. No que diz respeito ao trabalho, podem surgir muito <strong>cansa\u00e7o visual<\/strong> e dor de cabe\u00e7a ap\u00f3s horas diante do computador.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Boa parte da popula\u00e7\u00e3o brasileira tem o que chamamos de \u201cerros de refra\u00e7\u00e3o\u201d, que causa essa dificuldade e interfere na nitidez da imagem. Um deles \u00e9 a <strong>miopia<\/strong>, que atinge milh\u00f5es de pessoas. <\/span><span style=\"font-weight: 400;\">Esses problemas se caracterizam por defeitos na c\u00f3rnea, isto \u00e9, parte do olho respons\u00e1vel pela recep\u00e7\u00e3o da luz e pela forma\u00e7\u00e3o do foco da imagem visual.<\/span><\/p>\n<h1><b>Sobre os erros de refra\u00e7\u00e3o<\/b><\/h1>\n<p><span style=\"font-weight: 400;\">Entenda mais detalhes sobre estes problemas oculares:<\/span><\/p>\n<p><strong>Miopia:<\/strong> \u00e9 um erro de refra\u00e7\u00e3o em que a pessoa v\u00ea objetos pr\u00f3ximos com defini\u00e7\u00e3o, e os distantes, ficam emba\u00e7ados, sem nitidez. Ocorre quando o globo ocular \u00e9 ligeiramente mais longo do que o normal ou quando a c\u00f3rnea se curva muito. A imagem visual \u00e9 focada \u00e0 frente da retina, deixando fora de foco a vis\u00e3o distante. Ou seja: a pessoa enxerga bem de perto e mal de longe.<\/p>\n<p><strong>Hipermetropia:<\/strong> \u00e9 uma condi\u00e7\u00e3o em que a pessoa pode, com esfor\u00e7o, ver objetos distantes de forma clara, mas de perto enxerga sem nitidez, emba\u00e7ado. Ocorre quando o globo ocular \u00e9 mais curto do que a m\u00e9dia ou a c\u00f3rnea \u00e9 muito plana. A imagem visual \u00e9 focada atr\u00e1s da retina. Quando o grau \u00e9 muito alto em crian\u00e7as, pode causar estrabismo.<\/p>\n<p><strong>Astigmatismo:<\/strong> \u00e9 um erro de refra\u00e7\u00e3o que provoca vis\u00e3o, em geral, emba\u00e7ada. Ocorre quando a c\u00f3rnea se curva ou se achata de forma desigual. O resultado \u00e9 o astigmatismo, que interrompe o foco de vis\u00e3o pr\u00f3xima e distante.<\/p>\n<p><strong>Presbiopia (vista cansada):<\/strong> \u00e9 uma condi\u00e7\u00e3o natural do envelhecimento do cristalino. A capacidade de focar objetos pr\u00f3ximos diminui com o tempo em que o olho apresenta uma capacidade progressivamente diminu\u00edda para focar objetos pr\u00f3ximos.<\/p>\n<h2><b>Corre\u00e7\u00e3o dos problemas refrativos<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">\u00d3culos e lentes de contato s\u00e3o \u00f3timas solu\u00e7\u00f5es para os erros refrativos. Voc\u00ea pode receber sua receita, solicit\u00e1-los e dias depois recuperar a vis\u00e3o \u00f3tima ou pr\u00f3xima do ideal. Entretanto, algumas pessoas n\u00e3o se adaptam muito bem a essas duas op\u00e7\u00f5es. Por que isso pode acontecer:<\/span><\/p>\n<p><b>Acidentes e perdas<\/b><span style=\"font-weight: 400;\">: os \u00f3<\/span><span style=\"font-weight: 400;\">culos podem se perder ou quebrar. Principalmente na pr\u00e1tica de esportes. O mesmo pode se dar com as lentes, quando as pessoas se exp\u00f5em em lugares com muito vento, na <\/span><span style=\"font-weight: 400;\">piscina ou no mar, sem retir\u00e1-las.<\/span><\/p>\n<p><b>Limpeza:<\/b><span style=\"font-weight: 400;\"> \u00e9 preciso ter cuidado redobrado com a limpeza dos \u00f3culos e das lentes, que podem arranhar ou causar infec\u00e7\u00f5es, no caso das lentes de contato.<\/span><\/p>\n<p><b>Praticar esportes<\/b><span style=\"font-weight: 400;\">: atividades que requerem muito esfor\u00e7o f\u00edsico ou condi\u00e7\u00f5es extremas pode ser ainda mais dif\u00edcil, caso a pessoa utilize \u00f3culos e lentes de contato.<\/span><\/p>\n<p><b>Cansa\u00e7o visual: <\/b><span style=\"font-weight: 400;\">para quem trabalha no computador durante muitas horas, por exemplo, o uso de lentes pode causar muito desconforto visual.<\/span><\/p>\n<p><b>Troca constante:<\/b><span style=\"font-weight: 400;\"> sempre que o grau aumenta, \u00e9 necess\u00e1rio trocar os \u00f3culos. J\u00e1 as lentes, costumam ter data de validade, e \u00e9 necess\u00e1rio substitu\u00ed-las mesmo que o grau continue sem altera\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, para quem<\/span><span style=\"font-weight: 400;\"> n\u00e3o consegue se adaptar aos \u00f3culos e \u00e0s lentes ou acredita que os acess\u00f3rios s\u00e3o obst\u00e1culos que prejudicam a qualidade de vida, talvez seja bom considerar a interven\u00e7\u00e3o cir\u00fargica. A <\/span><a href=\"http:\/\/www.holhos.com.br\/portfolio-item\/cirurgia-refrativa\/\"><strong>cirurgia refrativa<\/strong><\/a><span style=\"font-weight: 400;\">\u00a0\u00e9 um procedimento a laser, eficaz e seguro, para corrigir <strong>miopia, hipermetropia, astigmatismo e presbiopia<\/strong>. As t\u00e9cnicas mais usadas s\u00e3o LASIK, PRK e Smile. Esses<\/span><span style=\"font-weight: 400;\"> s\u00e3o recursos altamente adotados para a corre\u00e7\u00e3o da c\u00f3rnea e faze<\/span><span style=\"font-weight: 400;\">m com que as imagens visuais sejam formadas com precis\u00e3o. \u00a0<\/span><\/p>\n<h2><b>Benef\u00edcios da cirurgia refrativa<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">A <strong>cirurgia refrativa<\/strong> \u00e9 um tratamento completo, com altas taxas de sucesso, e que pode reparar completamente os erros refrativos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hoje s\u00e3o utilizadas t\u00e9cnicas mais avan\u00e7adas, precisas e seguras para remodelagem da c\u00f3rnea que corrigem os erros de refra\u00e7\u00e3o que provocam a <\/span><b>Miopia<\/b><span style=\"font-weight: 400;\">, a <\/span><b>Hipermetropia<\/b><span style=\"font-weight: 400;\">, o <\/span><b>Astigmatismo<\/b><span style=\"font-weight: 400;\"> e a <\/span><b>Presbiopia<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O m\u00e9todo mais sofisticado de cirurgias refrativas a laser \u00e9 a t\u00e9cnica SMILE. Realizada com a tecnologia FemtoSecond Zeiss VisuMax\u00ae o processo cir\u00fargico \u00e9 altamente preciso, minimamente invasivo, o que possibilita uma recupera\u00e7\u00e3o ainda mais r\u00e1pida.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O <\/span><b>HOlhos<\/b><span style=\"font-weight: 400;\"> \u00e9 o centro de refer\u00eancia, pesquisa e treinamento exclusivo da fabricante alem\u00e3 Zeiss em Minas. A Zeiss \u00e9 \u2013 h\u00e1 mais de 170 anos \u2013 a maior refer\u00eancia mundial na produ\u00e7\u00e3o de lentes e equipamentos \u00f3pticos.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2006 size-full\" src=\"https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-614969896_Easy-Resize.com_.jpg\" alt=\"Imagem de um grupo de quatro pessoas correndo juntas \u00e0 noite, com ilumina\u00e7\u00e3o de rua ao fundo. Eles est\u00e3o sorrindo e usando roupas esportivas coloridas e confort\u00e1veis. O ambiente sugere um momento de atividade f\u00edsica ao ar livre, provavelmente parte de um treino em grupo ou corrida casual.\" width=\"1280\" height=\"853\" srcset=\"https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-614969896_Easy-Resize.com_.jpg 1280w, https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-614969896_Easy-Resize.com_-300x200.jpg 300w, https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-614969896_Easy-Resize.com_-1024x682.jpg 1024w, https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-614969896_Easy-Resize.com_-150x100.jpg 150w, https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-614969896_Easy-Resize.com_-768x512.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<h2><strong>Confira alguns benef\u00edcios da cirurgia refrativa:<\/strong><\/h2>\n<p><strong>Economia:<\/strong> al\u00e9m da mudan\u00e7a de grau e do vencimento das lentes, muitas pessoas perdem ou quebram seus \u00f3culos, o que pode onerar o seu or\u00e7amento. Quem tem seus problemas corrigidos normalmente para de investir em \u00f3culos ou em lentes de contato<\/p>\n<p><strong>Seguran\u00e7a, exatid\u00e3o do procedimento:<\/strong> \u00a0a cirurgia refrativa \u00e9 um procedimento que n\u00e3o requer interna\u00e7\u00e3o, sendo a recupera\u00e7\u00e3o p\u00f3s-operat\u00f3ria r\u00e1pida, o que possibilita o breve retorno \u00e0s atividades de rotina. O uso dos medicamentos no p\u00f3s-operat\u00f3rio se d\u00e1 por um curto per\u00edodo de tempo.<\/p>\n<p><strong>Independ\u00eancia:<\/strong> a pr\u00e1tica de esportes, as idas \u00e0 praia, os banhos de piscina, os passeios e as atividades ao ar livre voltam a ser poss\u00edveis com frequ\u00eancia, uma vez que n\u00e3o dependem dos \u00f3culos ou da busca por um lugar adequado e limpo para colocar ou retirar as lentes.<\/p>\n<p><strong>Maquiagem:<\/strong> muitas pessoas que usam \u00f3culos reclamam da dificuldade em aplicar maquiagem. Esse problema acaba depois da cirurgia refrativa, influindo positivamente at\u00e9 mesmo na autoestima das mulheres.<\/p>\n<h2><b>Procure uma institui\u00e7\u00e3o de excel\u00eancia para fazer a cirurgia refrativa<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea ou algu\u00e9m da sua fam\u00edlia decidir se submeter \u00e0 <strong>cirurgia refrativa<\/strong>, garanta que o cirurgi\u00e3o oftalmologista e o local do procedimento sejam de extrema confian\u00e7a. J\u00e1 existem no Brasil v\u00e1rios equipamentos avan\u00e7ados que aumentam a seguran\u00e7a do processo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, \u00e9 importante que o oftalmologista defina qual \u00e9 o melhor tipo de cirurgia para cada caso e se o estado de sa\u00fade geral da pessoa permite o tratamento. Isso s\u00f3 um profissional especializado e experiente poder\u00e1 dizer.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O <\/span><a href=\"http:\/\/www.holhos.com.br\/\"><b>Hospital de Olhos Dr. Ricardo Guimar\u00e3es<\/b><\/a><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">\u00e9 pioneiro em cirurgias refrativas no Br<\/span><span style=\"font-weight: 400;\">asil e refer<\/span><span style=\"font-weight: 400;\">\u00eancia mundial no tratamento de dist\u00farbios da vis\u00e3o. Conte com a nossa equipe m\u00e9dica e infraestrutura moderna e equipada com o que h\u00e1 de mais avan\u00e7ado no mundo para o procedimento das cirurgias oculares.<\/span><\/p>\n<p>Entre em contato conosco hoje mesmo e <a href=\"https:\/\/holhos.com.br\/blog\/?MarqueConsulta=1\"><strong>marque uma consulta<\/strong><\/a><strong>!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conhe\u00e7a os erros de refra\u00e7\u00e3o, como podem ser corrigidos e os benef\u00edcios da cirurgia refrativa.<\/p>\n","protected":false},"author":13,"featured_media":358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[15],"class_list":["post-351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tratamentos","tag-cirurgia-refrativa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saiba o que \u00e9 cirurgia refrativa e conhe\u00e7a seus benef\u00edcios - HOlhos<\/title>\n<meta name=\"description\" content=\"Miopia e hipermetropia s\u00e3o problemas de vis\u00e3o bem conhecidos. Mas sabia que \u00e9 poss\u00edvel corrigir esses problemas? Conhe\u00e7a a cirurgia refrativa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saiba o que \u00e9 cirurgia refrativa e conhe\u00e7a seus benef\u00edcios - HOlhos\" \/>\n<meta property=\"og:description\" content=\"Miopia e hipermetropia s\u00e3o problemas de vis\u00e3o bem conhecidos. Mas sabia que \u00e9 poss\u00edvel corrigir esses problemas? Conhe\u00e7a a cirurgia refrativa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/\" \/>\n<meta property=\"og:site_name\" content=\"HOlhos\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-04T13:04:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T17:30:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-626535710.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1256\" \/>\n\t<meta property=\"og:image:height\" content=\"835\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ComunicacaoHolhos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ComunicacaoHolhos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/\"},\"author\":{\"name\":\"ComunicacaoHolhos\",\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/542dd993649f9438b19cdbf2540be23d\"},\"headline\":\"O que \u00e9 cirurgia refrativa? Conhe\u00e7a os benef\u00edcios do procedimento\",\"datePublished\":\"2017-12-04T13:04:10+00:00\",\"dateModified\":\"2025-06-17T17:30:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/\"},\"wordCount\":1235,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/iStock-626535710.jpg\",\"keywords\":[\"cirurgia refrativa\"],\"articleSection\":[\"Tratamentos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/\",\"url\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/\",\"name\":\"Saiba o que \u00e9 cirurgia refrativa e conhe\u00e7a seus benef\u00edcios - HOlhos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/iStock-626535710.jpg\",\"datePublished\":\"2017-12-04T13:04:10+00:00\",\"dateModified\":\"2025-06-17T17:30:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/542dd993649f9438b19cdbf2540be23d\"},\"description\":\"Miopia e hipermetropia s\u00e3o problemas de vis\u00e3o bem conhecidos. Mas sabia que \u00e9 poss\u00edvel corrigir esses problemas? Conhe\u00e7a a cirurgia refrativa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/iStock-626535710.jpg\",\"contentUrl\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/iStock-626535710.jpg\",\"width\":1256,\"height\":835,\"caption\":\"cirurgia refrativa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/o-que-e-cirurgia-refrativa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 cirurgia refrativa? Conhe\u00e7a os benef\u00edcios do procedimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/\",\"name\":\"HOlhos\",\"description\":\"Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/holhos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/542dd993649f9438b19cdbf2540be23d\",\"name\":\"ComunicacaoHolhos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3db906490c4168995a69a1c434230a85239247ef3b6e0a1f6348720043cdda91?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3db906490c4168995a69a1c434230a85239247ef3b6e0a1f6348720043cdda91?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3db906490c4168995a69a1c434230a85239247ef3b6e0a1f6348720043cdda91?s=96&d=mm&r=g\",\"caption\":\"ComunicacaoHolhos\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saiba o que \u00e9 cirurgia refrativa e conhe\u00e7a seus benef\u00edcios - HOlhos","description":"Miopia e hipermetropia s\u00e3o problemas de vis\u00e3o bem conhecidos. Mas sabia que \u00e9 poss\u00edvel corrigir esses problemas? Conhe\u00e7a a cirurgia refrativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/","og_locale":"pt_BR","og_type":"article","og_title":"Saiba o que \u00e9 cirurgia refrativa e conhe\u00e7a seus benef\u00edcios - HOlhos","og_description":"Miopia e hipermetropia s\u00e3o problemas de vis\u00e3o bem conhecidos. Mas sabia que \u00e9 poss\u00edvel corrigir esses problemas? Conhe\u00e7a a cirurgia refrativa.","og_url":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/","og_site_name":"HOlhos","article_published_time":"2017-12-04T13:04:10+00:00","article_modified_time":"2025-06-17T17:30:55+00:00","og_image":[{"width":1256,"height":835,"url":"https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-626535710.jpg","type":"image\/jpeg"}],"author":"ComunicacaoHolhos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ComunicacaoHolhos","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/#article","isPartOf":{"@id":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/"},"author":{"name":"ComunicacaoHolhos","@id":"https:\/\/holhos.com.br\/blog\/#\/schema\/person\/542dd993649f9438b19cdbf2540be23d"},"headline":"O que \u00e9 cirurgia refrativa? Conhe\u00e7a os benef\u00edcios do procedimento","datePublished":"2017-12-04T13:04:10+00:00","dateModified":"2025-06-17T17:30:55+00:00","mainEntityOfPage":{"@id":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/"},"wordCount":1235,"commentCount":0,"image":{"@id":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/#primaryimage"},"thumbnailUrl":"https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-626535710.jpg","keywords":["cirurgia refrativa"],"articleSection":["Tratamentos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/","url":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/","name":"Saiba o que \u00e9 cirurgia refrativa e conhe\u00e7a seus benef\u00edcios - HOlhos","isPartOf":{"@id":"https:\/\/holhos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/#primaryimage"},"image":{"@id":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/#primaryimage"},"thumbnailUrl":"https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-626535710.jpg","datePublished":"2017-12-04T13:04:10+00:00","dateModified":"2025-06-17T17:30:55+00:00","author":{"@id":"https:\/\/holhos.com.br\/blog\/#\/schema\/person\/542dd993649f9438b19cdbf2540be23d"},"description":"Miopia e hipermetropia s\u00e3o problemas de vis\u00e3o bem conhecidos. Mas sabia que \u00e9 poss\u00edvel corrigir esses problemas? Conhe\u00e7a a cirurgia refrativa.","breadcrumb":{"@id":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/#primaryimage","url":"https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-626535710.jpg","contentUrl":"https:\/\/holhos.com.br\/blog\/wp-content\/uploads\/iStock-626535710.jpg","width":1256,"height":835,"caption":"cirurgia refrativa"},{"@type":"BreadcrumbList","@id":"https:\/\/holhos.com.br\/blog\/o-que-e-cirurgia-refrativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/holhos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 cirurgia refrativa? Conhe\u00e7a os benef\u00edcios do procedimento"}]},{"@type":"WebSite","@id":"https:\/\/holhos.com.br\/blog\/#website","url":"https:\/\/holhos.com.br\/blog\/","name":"HOlhos","description":"Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/holhos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/holhos.com.br\/blog\/#\/schema\/person\/542dd993649f9438b19cdbf2540be23d","name":"ComunicacaoHolhos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3db906490c4168995a69a1c434230a85239247ef3b6e0a1f6348720043cdda91?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3db906490c4168995a69a1c434230a85239247ef3b6e0a1f6348720043cdda91?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3db906490c4168995a69a1c434230a85239247ef3b6e0a1f6348720043cdda91?s=96&d=mm&r=g","caption":"ComunicacaoHolhos"}}]}},"_links":{"self":[{"href":"https:\/\/holhos.com.br\/blog\/wp-json\/wp\/v2\/posts\/351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holhos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holhos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holhos.com.br\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/holhos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=351"}],"version-history":[{"count":22,"href":"https:\/\/holhos.com.br\/blog\/wp-json\/wp\/v2\/posts\/351\/revisions"}],"predecessor-version":[{"id":2188,"href":"https:\/\/holhos.com.br\/blog\/wp-json\/wp\/v2\/posts\/351\/revisions\/2188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holhos.com.br\/blog\/wp-json\/wp\/v2\/media\/358"}],"wp:attachment":[{"href":"https:\/\/holhos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holhos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holhos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}